{"id":37826,"date":"2025-04-10T16:23:20","date_gmt":"2025-04-10T14:23:20","guid":{"rendered":"https:\/\/www.atmosferamag.it\/?p=37826"},"modified":"2025-04-10T16:30:12","modified_gmt":"2025-04-10T14:30:12","slug":"euroluce-2025-illuminazione-salone-design-week-milano","status":"publish","type":"post","link":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/","title":{"rendered":"Euroluce 2025: i 5 allestimenti che hanno lasciato il segno durante la Milano Design Week"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37826\" class=\"elementor elementor-37826\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b08cc3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b08cc3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99837cd\" data-id=\"99837cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecd10f1 elementor-widget elementor-widget-text-editor\" data-id=\"ecd10f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ricomincia la biennale firmata <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.salonemilano.it\/it\" target=\"_blank\" rel=\"noopener\"><b>Salone del Mobile.Milano<\/b><\/a><\/span><span style=\"font-weight: 400;\"> dedicata al mondo del lighting: <\/span><a href=\"https:\/\/www.salonemilano.it\/it\/manifestazioni\/euroluce\" target=\"_blank\" rel=\"noopener\"><b><span style=\"text-decoration: underline;\">Euroluce 2025<\/span><\/b><\/a> <span style=\"font-weight: 400;\">ha inaugurato ieri con i suoi <\/span><b>300 espositori<\/b><span style=\"font-weight: 400;\"> e <\/span><b>un nuovo format culturale<\/b><span style=\"font-weight: 400;\">,<\/span><i><span style=\"font-weight: 400;\"> The Euroluce International Lighting Forum<\/span><\/i><span style=\"font-weight: 400;\">, un dialogo internazionale sui grandi temi della progettazione della luce. <\/span><span style=\"font-weight: 400;\"><br \/><br \/><\/span><\/p><p><span style=\"font-weight: 400;\">L\u2019evento non \u00e8 solo un\u2019occasione per mostrare le proprie novit\u00e0, ma anche <\/span><b>un vero e proprio palcoscenico per i diversi brand italiani e internazionali<\/b><span style=\"font-weight: 400;\">: \u00e8 un\u2019opportunit\u00e0 per lasciare il segno creando spazi ed esperienze che i visitatori non dimenticheranno. <\/span><b>Abbiamo quindi selezionato i 5 stand pi\u00f9 suggestivi progettati per Euroluce 2025<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c047c38 elementor-widget elementor-widget-text-editor\" data-id=\"c047c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Calvi Brambilla per Platek<\/h2><p><a href=\"https:\/\/www.platek.eu\/ita\/\"><b>Platek<\/b><\/a><span style=\"font-weight: 400;\"> partecipa a Euroluce 2025 con <\/span><i><span style=\"font-weight: 400;\">\u201cA Different Landscape\u201d<\/span><\/i><span style=\"font-weight: 400;\">, lo stand <\/span><b>progettato dallo studio <\/b><a href=\"https:\/\/www.calvibrambilla.it\/\"><b>Calvi Brambilla<\/b><\/a> <span style=\"font-weight: 400;\">che porta il visitatore in una vera e propria architettura effimera, lontano dalla fiera. Un percorso che vuole simulare un paesaggio notturno e le sensazioni che si provano attraversandolo, in questo caso camminando su passerelle sopraelevate in legno. Una maglia di pilastri e travi sorregge un grigliato metallico che ha la funzione di filtro con l\u2019esterno, ma non opprime lo spazio.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f363e77 elementor-widget elementor-widget-image\" data-id=\"f363e77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"641\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek-1024x820.jpg\" class=\"attachment-large size-large wp-image-37839\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek-1024x820.jpg 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek-300x240.jpg 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek-768x615.jpg 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek-1536x1230.jpg 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03d7d71 elementor-widget elementor-widget-text-editor\" data-id=\"03d7d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Il percorso di visita non \u00e8 solo un\u2019esperienza visiva: elementi sonori e olfattivi aiutano a rimanere avvolti in questo viaggio, apprezzando la qualit\u00e0 e l\u2019atmosfera creata dai prodotti per esterni di Platek.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82eb796 elementor-widget elementor-widget-image\" data-id=\"82eb796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"592\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2-1024x758.png\" class=\"attachment-large size-large wp-image-37849\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2-1024x758.png 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2-300x222.png 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2-768x568.png 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2-1536x1137.png 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/platek2.png 1678w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-759254b elementor-widget elementor-widget-text-editor\" data-id=\"759254b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Gian Paolo Venier \u2013 Otto studio per Siru Lighting<\/h2><p><span style=\"font-weight: 400;\">Come ci racconta <\/span><b>Gian Paolo Venier <\/b><span style=\"font-weight: 400;\">di <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/otto.fish\/\" target=\"_blank\" rel=\"noopener\"><b>Otto studio<\/b><\/a><\/span><span style=\"font-weight: 400;\">, <\/span><i><span style=\"font-weight: 400;\">\u201clo spazio di <\/span><\/i><span style=\"text-decoration: underline;\"><a href=\"http:\/\/siru.com\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Siru<\/span><\/i><\/a><\/span><i><span style=\"font-weight: 400;\"> nasce dalla<\/span><\/i> <i><span style=\"font-weight: 400;\">volont\u00e0 di creare uno stand totalmente tessile, superando l\u2019idea dei tendaggi\u2026 Come in altri progetti, mi piace utilizzare un materiale in un contesto diverso rispetto al suo normale utilizzo\u201d<\/span><\/i><span style=\"font-weight: 400;\">. La scelta \u00e8 quindi ricaduta su un tessuto industriale in fibra di vetro da un lato e con una pellicola di alluminio dall\u2019altro.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d1545c elementor-widget elementor-widget-image\" data-id=\"0d1545c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"641\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1-1024x820.jpg\" class=\"attachment-large size-large wp-image-37851\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1-1024x820.jpg 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1-300x240.jpg 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1-768x615.jpg 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1-1536x1230.jpg 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/siru-1.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f96b56 elementor-widget elementor-widget-text-editor\" data-id=\"6f96b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Attraverso la collaborazione con artigiani tappezzieri \u2013 dato il materiale, una sfida per loro \u2013 il tessuto \u00e8 stato cucito creando un effetto trapuntato, come un piumino. Lo spazio presenta elementi imbottiti e il materiale, dalle forme stropicciate e con un effetto luminoso profondo, dialoga per contrasto con le soluzioni luminose esposte.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff99f9d elementor-widget elementor-widget-image\" data-id=\"ff99f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"669\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55-1024x856.png\" class=\"attachment-large size-large wp-image-37853\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55-1024x856.png 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55-300x251.png 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55-768x642.png 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55-1536x1283.png 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Schermata-2025-04-10-alle-16.26.55.png 1788w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253e454 elementor-widget elementor-widget-text-editor\" data-id=\"253e454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>VRTI\u0160KA &amp; \u017d\u00c1K per Brokis<\/h2><p><span style=\"font-weight: 400;\">Un altro stand particolarmente suggestivo \u00e8 quello di<\/span> <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.brokis.cz\/\" target=\"_blank\" rel=\"noopener\"><b>Brokis<\/b><\/a><\/span><span style=\"font-weight: 400;\">, <\/span><b>disegnato dal duo ceco <\/b><span style=\"text-decoration: underline;\"><a href=\"https:\/\/vrtiskazak.com\/\" target=\"_blank\" rel=\"noopener\"><b>VRTI\u0160KA &amp; \u017d\u00c1K<\/b><\/a><\/span><span style=\"font-weight: 400;\">. In questo caso, come ci racconta direttamente lo studio, il concept \u00e8 quello di mantenere uno spazio aperto che invita il visitatore a scoprire le collezioni, ma allo stesso tempo in movimento, in grado di dare il giusto set a ogni soluzione luminosa senza utilizzare pareti o soluzioni visivamente pesanti. Per realizzarlo \u00e8 stato utilizzato un sistema a soffitto che guida lentamente dei tessuti pregiati di diverse altezze in un percorso sinuoso: il movimento rivela le nuove collezioni ma crea anche spazi con maggiore privacy, necessari per buyers e agenti.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6faadb9 elementor-widget elementor-widget-image\" data-id=\"6faadb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie-1024x1024.jpg\" class=\"attachment-large size-large wp-image-37855\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie-1024x1024.jpg 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie-300x300.jpg 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie-150x150.jpg 150w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie-768x767.jpg 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/Brokis__PH16386_\u00a9_Martin_Chum-kopie.jpg 1421w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-770e687 elementor-widget elementor-widget-text-editor\" data-id=\"770e687\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>La sostenibilit\u00e0 di Midgard<\/h2><p><span style=\"font-weight: 400;\">La sostenibilit\u00e0 \u00e8 al centro dell\u2019identit\u00e0 di<\/span> <span style=\"text-decoration: underline;\"><a href=\"https:\/\/midgard.com\/\" target=\"_blank\" rel=\"noopener\"><b>Midgard<\/b><\/a><\/span><span style=\"font-weight: 400;\"> che porta a Euroluce 2025 un allestimento di 90mq semplice, modulare e riutilizzabile, creato con materiali riciclati e riciclabili: cartone e acciaio stagnato (a basso tenore di carbonio). Le pareti in cartone e le scaffalature in acciaio autoportanti e senza bulloni definiscono lo stand che nella parte anteriore presenta uno spazio showroom con le ultime novit\u00e0. Intorno a questo, si sviluppano piccole scenografie che, grazie anche alla combinazione con arredi di fascia alta, riproducono zone living e spazi di lavoro ambientando al meglio le soluzioni luminose. Le pareti e le scaffalature possono essere facilmente disassemblate e riutilizzate in altre fiere.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2194f98 elementor-widget elementor-widget-image\" data-id=\"2194f98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"641\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1-1024x820.jpg\" class=\"attachment-large size-large wp-image-37857\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1-1024x820.jpg 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1-300x240.jpg 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1-768x615.jpg 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1-1536x1230.jpg 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/midgard-1.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60dd177 elementor-widget elementor-widget-text-editor\" data-id=\"60dd177\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Nichetto Studio per Barovier&amp;Toso<\/h2><p><a href=\"https:\/\/www.barovier.com\/it\" target=\"_blank\" rel=\"noopener\"><b><span style=\"text-decoration: underline;\">Barovier&amp;Toso<\/span><\/b><\/a><span style=\"font-weight: 400;\"> sceglie<\/span> <a href=\"https:\/\/www.nichettostudio.com\/\" target=\"_blank\" rel=\"noopener\"><b><span style=\"text-decoration: underline;\">Nichetto Studio<\/span><\/b><\/a><span style=\"font-weight: 400;\"> per portare la sua arte a Euroluce 2025. Lo studio con sede a Venezia e Stoccolma pensa per il brand uno spazio d\u2019impatto che ricorda una galleria italiana. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-114fd51 elementor-widget elementor-widget-image\" data-id=\"114fd51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"641\" src=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier-1024x820.jpg\" class=\"attachment-large size-large wp-image-37837\" alt=\"\" srcset=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier-1024x820.jpg 1024w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier-300x240.jpg 300w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier-768x615.jpg 768w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier-1536x1230.jpg 1536w, https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/barovier.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">3. Sou Fujimoto. Forest of Space - Original Concept Sketch. Salone del Mobile.Milano 2025 \u00a9Sou Fujimoto Architect<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a9ceb elementor-widget elementor-widget-text-editor\" data-id=\"53a9ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u00a0Da lontano, grandi forme irregolari rosse \u2013 che ricordano il vetro appena estratto dalla fornace, prima di essere lavorato \u2013 invitano il visitatore a percorrere la galleria a L che presenta prima alcune nicchie (a ricordare le vetrine dei negozi) e lascia poi spazio a un corridoio aperto, limitato da una cascata di luce, che porta in un\u2019area meno esposta, un interno pulito di grandi dimensioni in cui sono le composizioni dei prodotti e i colori a parlare.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Una selezione delle architetture temporanee pi\u00f9 belle create dai lighting brand per Euroluce 2025. Scopri la selezione.<\/p>\n","protected":false},"author":19,"featured_media":37847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-37826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-highlights"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag<\/title>\n<meta name=\"description\" content=\"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag\" \/>\n<meta property=\"og:description\" content=\"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Atmosfera Mag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Atmosfera-Mag\/100086538670476\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T14:23:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T14:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover-1024x749.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Teo Sandigliano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teo Sandigliano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/\"},\"author\":{\"name\":\"Teo Sandigliano\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#\\\/schema\\\/person\\\/19b178a6d612d6fd0de5416801c007a2\"},\"headline\":\"Euroluce 2025: i 5 allestimenti che hanno lasciato il segno durante la Milano Design Week\",\"datePublished\":\"2025-04-10T14:23:20+00:00\",\"dateModified\":\"2025-04-10T14:30:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/\"},\"wordCount\":697,\"publisher\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cover.png\",\"articleSection\":[\"Highlights\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/\",\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/\",\"name\":\"Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cover.png\",\"datePublished\":\"2025-04-10T14:23:20+00:00\",\"dateModified\":\"2025-04-10T14:30:12+00:00\",\"description\":\"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cover.png\",\"contentUrl\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cover.png\",\"width\":1558,\"height\":1140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/euroluce-2025-illuminazione-salone-design-week-milano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euroluce 2025: i 5 allestimenti che hanno lasciato il segno durante la Milano Design Week\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/\",\"name\":\"Atmosfera Mag\",\"description\":\"La luce in tutte le sue forme\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#organization\",\"name\":\"Atmosfera Mag\",\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/titolo.png\",\"contentUrl\":\"https:\\\/\\\/www.atmosferamag.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/titolo.png\",\"width\":2728,\"height\":406,\"caption\":\"Atmosfera Mag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Atmosfera-Mag\\\/100086538670476\\\/\",\"https:\\\/\\\/www.instagram.com\\\/atmosferamag\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/atmosfera_mag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/#\\\/schema\\\/person\\\/19b178a6d612d6fd0de5416801c007a2\",\"name\":\"Teo Sandigliano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g\",\"caption\":\"Teo Sandigliano\"},\"url\":\"https:\\\/\\\/www.atmosferamag.it\\\/it\\\/author\\\/teo-sandigliano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag","description":"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/","og_locale":"it_IT","og_type":"article","og_title":"Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag","og_description":"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.","og_url":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/","og_site_name":"Atmosfera Mag","article_publisher":"https:\/\/www.facebook.com\/people\/Atmosfera-Mag\/100086538670476\/","article_published_time":"2025-04-10T14:23:20+00:00","article_modified_time":"2025-04-10T14:30:12+00:00","og_image":[{"width":1024,"height":749,"url":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover-1024x749.png","type":"image\/png"}],"author":"Teo Sandigliano","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Teo Sandigliano","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#article","isPartOf":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/"},"author":{"name":"Teo Sandigliano","@id":"https:\/\/www.atmosferamag.it\/it\/#\/schema\/person\/19b178a6d612d6fd0de5416801c007a2"},"headline":"Euroluce 2025: i 5 allestimenti che hanno lasciato il segno durante la Milano Design Week","datePublished":"2025-04-10T14:23:20+00:00","dateModified":"2025-04-10T14:30:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/"},"wordCount":697,"publisher":{"@id":"https:\/\/www.atmosferamag.it\/it\/#organization"},"image":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover.png","articleSection":["Highlights"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/","url":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/","name":"Euroluce 2025: gli stand luce pi\u00f9 sorprendenti | Atmosfera Mag","isPartOf":{"@id":"https:\/\/www.atmosferamag.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#primaryimage"},"image":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover.png","datePublished":"2025-04-10T14:23:20+00:00","dateModified":"2025-04-10T14:30:12+00:00","description":"Gli allestimenti pi\u00f9 suggestivi di Euroluce 2025 alla Milano Design Week: 300 espositori e un nuovo format culturale sull\u2019illuminazione.","breadcrumb":{"@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#primaryimage","url":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover.png","contentUrl":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2025\/04\/cover.png","width":1558,"height":1140},{"@type":"BreadcrumbList","@id":"https:\/\/www.atmosferamag.it\/it\/euroluce-2025-illuminazione-salone-design-week-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atmosferamag.it\/it\/"},{"@type":"ListItem","position":2,"name":"Euroluce 2025: i 5 allestimenti che hanno lasciato il segno durante la Milano Design Week"}]},{"@type":"WebSite","@id":"https:\/\/www.atmosferamag.it\/it\/#website","url":"https:\/\/www.atmosferamag.it\/it\/","name":"Atmosfera Mag","description":"La luce in tutte le sue forme","publisher":{"@id":"https:\/\/www.atmosferamag.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atmosferamag.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.atmosferamag.it\/it\/#organization","name":"Atmosfera Mag","url":"https:\/\/www.atmosferamag.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atmosferamag.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2022\/09\/titolo.png","contentUrl":"https:\/\/www.atmosferamag.it\/wp-content\/uploads\/2022\/09\/titolo.png","width":2728,"height":406,"caption":"Atmosfera Mag"},"image":{"@id":"https:\/\/www.atmosferamag.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Atmosfera-Mag\/100086538670476\/","https:\/\/www.instagram.com\/atmosferamag\/","https:\/\/www.pinterest.it\/atmosfera_mag\/"]},{"@type":"Person","@id":"https:\/\/www.atmosferamag.it\/it\/#\/schema\/person\/19b178a6d612d6fd0de5416801c007a2","name":"Teo Sandigliano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/376ecd71b23f0f2590bd2c47d3ed9825a0e839bdfdcfc353b8b9a7502d635b07?s=96&d=mm&r=g","caption":"Teo Sandigliano"},"url":"https:\/\/www.atmosferamag.it\/it\/author\/teo-sandigliano\/"}]}},"_links":{"self":[{"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/posts\/37826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/comments?post=37826"}],"version-history":[{"count":13,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/posts\/37826\/revisions"}],"predecessor-version":[{"id":37861,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/posts\/37826\/revisions\/37861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/media\/37847"}],"wp:attachment":[{"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/media?parent=37826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/categories?post=37826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atmosferamag.it\/it\/wp-json\/wp\/v2\/tags?post=37826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}